{"id":241,"date":"2025-07-10T12:48:40","date_gmt":"2025-07-10T10:48:40","guid":{"rendered":"http:\/\/10.101.10.35\/wordpress\/?p=241"},"modified":"2026-02-02T11:22:59","modified_gmt":"2026-02-02T10:22:59","slug":"aussen-ein-laecheln-innen-verletzt-diskriminierung-muss-an-unserer-schule-mehr-beleuchtet-werden","status":"publish","type":"post","link":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/2025\/07\/10\/aussen-ein-laecheln-innen-verletzt-diskriminierung-muss-an-unserer-schule-mehr-beleuchtet-werden\/","title":{"rendered":"Au\u00dfen ein L\u00e4cheln, innen verletzt &#8211; Diskriminierung muss an unserer Schule mehr beleuchtet werden"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" style=\"letter-spacing:2px\"><em>\u201eMan kann ja nicht sagen, wir nehmen jetzt diese Sch\u00fclerin hier und setzen die in den Zug zur\u00fcck nach wohin auch immer\u2026\u201c Dieses Beispiel zeigt, wie leicht rassistische Doppelmoral entstehen kann: Der Satz stammt aus dem Mund einer Lehrkraft und er fiel im Unterricht w\u00e4hrend einer Diskussion zur aktuellen Abschiebepolitik. Doch als Beispiel genannt wurde die Sch\u00fclerin aufgrund ihrer Hautfarbe. Die Sch\u00fclerin lachte nach au\u00dfen hin, f\u00fchlte sich jedoch sichtbar diskriminiert. Solche Momente werfen die Fragen auf: Wie gro\u00df ist das Problem der Diskriminierung an unserer Schule? Und was wird dagegen getan?<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.6\">Auch an dieser Schule finden sich viele, auch gr\u00f6\u00dfere Facetten der Diskriminierung. Viele M\u00e4dchen passen nicht in die Norm der anderen, sie tragen nicht die richtige Kleidung oder das neuste Make-Up-Produkt. Auch sogenannte \u201eNerds\u201c werden bel\u00e4chelt. Nat\u00fcrlich ist die Toleranz gegen\u00fcber individuellen Personen heute gr\u00f6\u00dfer. Es zeigt sich jedoch immer noch eine Diskriminierung mit dem Ausschlie\u00dfen aus Gruppen, dem Gel\u00e4chter in den hinteren Reihen im Klassenraum. Und es gibt weitere Beispiele: Die Integrationskr\u00e4fte unterst\u00fctzen die Lehrkr\u00e4fte, d\u00fcrfen aber nicht ins Lehrerzimmer, die Sch\u00fcler der internationalen Klassen sollen nicht an der SV teilhaben, unter anderem weil sie ,,sowieso nichts verstehen\u201d. Kriegen wir so etwas \u00fcberhaupt mit? Ist unsere Schule dazu genug ausgebildet?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.6\">Die Antwort ist leider Nein. Auf dem Papier tut unsere Schule vieles gegen diese Diskriminierung. Werfen wir einen Blick auf die Homepage der Schule: \u201eMit R\u00fccksicht auf die Komplexit\u00e4t gesellschaftlicher Probleme wollen wir dennoch den Sinn f\u00fcrs Ideal wiedergewinnen\u201c, hei\u00dft es auf der Homepage der Schule unter dem Punkt \u201eKongressarbeit\u201c. Doch der letzte Kongress liegt schon ein paar Jahre zur\u00fcck.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.6\">Auch die Arbeitsgruppe f\u00fcr Inklusion fokussiert sich auf notwendige Weiterentwicklungen und pers\u00f6nliche Haltungen. Kreativit\u00e4t und Eigeninitiative f\u00fcr Zufriedenheit und gute Atmosph\u00e4re sind ein gro\u00dfes Verlangen unserer Schule. Wir versuchen Strukturen zu nutzen. Wir versuchen die Bedingungen so gestalten, dass sie den betroffenen Kindern gerecht werden. Die Gesamtschule Barmen versucht Bildung, Toleranz und Zivilcourage mithilfe von Videos, Podcasts und auch mithilfe der Sch\u00fclerzeitung weiter zu verbreiten. Themen, die Sch\u00fcler selbst besch\u00e4ftigen, stehen im Fokus. Damit kann Demokratie, zivilgesellschaftliches Engagement, Rechtspopulismus und Rassismus mehr beleuchtet werden. Doch reicht eine einzige Diskussion in der Universit\u00e4t w\u00e4hrend der Projektwoche? Diese Themen werden schlie\u00dflich seit 15 Jahren bei uns in der Schule angesprochen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.6\">Doch trotz vieler Texte und Ver\u00f6ffentlichungen auf der Homepage fehlt mir der<br>konkrete Einsatz. Dadurch beweist sich: Diskriminierung muss an unserer Schule mehr beleuchtet werden!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eMan kann ja nicht sagen, wir nehmen jetzt diese Sch\u00fclerin hier und setzen die in den Zug zur\u00fcck nach wohin auch immer\u2026\u201c Dieses Beispiel zeigt, wie leicht rassistische Doppelmoral entstehen kann: Der Satz stammt aus dem Mund einer Lehrkraft und er fiel im Unterricht w\u00e4hrend einer Diskussion zur aktuellen Abschiebepolitik. Doch als Beispiel genannt wurde [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":242,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politikundgesellschaft"],"_links":{"self":[{"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/posts\/241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/comments?post=241"}],"version-history":[{"count":4,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/posts\/241\/revisions"}],"predecessor-version":[{"id":583,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/posts\/241\/revisions\/583"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/media\/242"}],"wp:attachment":[{"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/media?parent=241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/categories?post=241"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/tags?post=241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}