{"id":266,"date":"2025-07-25T10:10:30","date_gmt":"2025-07-25T08:10:30","guid":{"rendered":"http:\/\/10.101.10.35\/wordpress\/?p=266"},"modified":"2025-11-27T08:42:08","modified_gmt":"2025-11-27T07:42:08","slug":"so-teuer-ist-die-schule-eine-spurensuche-niklas-s-5d","status":"publish","type":"post","link":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/2025\/07\/25\/so-teuer-ist-die-schule-eine-spurensuche-niklas-s-5d\/","title":{"rendered":"So teuer ist die Schule &#8211; eine Spurensuche (Niklas S., 5d)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" style=\"letter-spacing:2px\"><em>Ich habe mich schon lange gefragt, wie teuer die Schule ist \u2013 und das ist dabei herausgekommen!<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.6\">Nr. 1: Ich habe mich schon lange gefragt, wie teuer der Aufbau der Schule war. Um das herauszufinden, bin ich zur Schulleitung gegangen und habe Herrn Brassat gefragt. Er hat mir gesagt, dass 34 Millionen Euro \u201cbillig\u201d seien \u2013 also: Der Aufbau hat 34 Millionen Euro gekostet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.6\">Nr. 2: An der Gesamtschule Barmen gibt es mehrere Trakte. Die M\u00f6bel f\u00fcr einen Trakt kosten 18.108 Euro \u2013 und das dreimal ergibt 54.324 Euro. Also kosten alle M\u00f6bel zusammen 54.324 Euro. Die M\u00f6bel kosten 18.000 Euro, und die Uhren 108 Euro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.6\">Nr. 3: Alle B\u00fccher kosten zusammen 16.800 Euro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.6\">Nr. 4: Als ich \u00fcberlegte, was ich noch \u00fcber mein Thema schreiben k\u00f6nnte, kam mir eine Idee: die K\u00fcche! Also ging ich zu Herrn Zoch und dachte, ich bek\u00e4me nur eine Zahl, doch er bot mir an, mir die K\u00fcche zu zeigen. Da ich noch nie dort war und dachte, dass ich dort einen Hinweis finden k\u00f6nnte, willigte ich ein. Dort angekommen, fragte ich ihn sehr viel \u2013 zum Beispiel, wie viel die Sp\u00fclstra\u00dfe kostete. Alle \u00d6fen kosten 50.000 Euro, die Sp\u00fclstra\u00dfe 120.000<br>Euro und die beiden K\u00fchlh\u00e4user 240.000 Euro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.6\">Nr. 5: Als ich mich dazu entschied, \u00fcber den Digitalpakt zu schreiben, ging ich zu Herrn Overath und habe ihn gefragt. Er sagte mir, dass alles zusammen ca. 500.000 Euro gekostet hat. Die Anschaffung selbst hat 200.000 Euro gekostet. Fast h\u00e4tte ich die Laptops vergessen \u2013 die haben 520.000 Euro gekostet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.6\">Nun war die B\u00fccherei an der Reihe. Also ging ich mit meinem Freund dorthin, wir haben nachgefragt und herausgefunden, dass die B\u00fccher 200.000 Euro gekostet haben. Die B\u00fccherregale haben 300.000 Euro gekostet. Also hat die B\u00fccherei insgesamt 500.000 Euro gekostet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.6\">Der Versuch, die Kosten der Turnhalle herauszufinden, ist gescheitert.<br>Nach all der Zeit ist es endlich soweit: Die Schule hat fast 36.000.000 Euro<br>gekostet!!!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich habe mich schon lange gefragt, wie teuer die Schule ist \u2013 und das ist dabei herausgekommen! Nr. 1: Ich habe mich schon lange gefragt, wie teuer der Aufbau der Schule war. Um das herauszufinden, bin ich zur Schulleitung gegangen und habe Herrn Brassat gefragt. Er hat mir gesagt, dass 34 Millionen Euro \u201cbillig\u201d seien [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":267,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,11],"tags":[],"class_list":["post-266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politikundgesellschaft","category-junior"],"_links":{"self":[{"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/posts\/266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/comments?post=266"}],"version-history":[{"count":3,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/posts\/266\/revisions"}],"predecessor-version":[{"id":455,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/posts\/266\/revisions\/455"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/media\/267"}],"wp:attachment":[{"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/media?parent=266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/categories?post=266"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/tags?post=266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}