{"id":31,"date":"2024-12-13T12:39:32","date_gmt":"2024-12-13T11:39:32","guid":{"rendered":"http:\/\/10.101.10.35\/wordpress\/?p=31"},"modified":"2025-12-07T15:13:22","modified_gmt":"2025-12-07T14:13:22","slug":"lehrermangel-und-kein-ende","status":"publish","type":"post","link":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/2024\/12\/13\/lehrermangel-und-kein-ende\/","title":{"rendered":"Lehrermangel und kein Ende? &#8211; Wie sich der Lehrermangel auf unsere Schule auswirkt"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" style=\"letter-spacing:2px\"><em>Mathematik wird von drei Stunden die Woche auf zwei gek\u00fcrzt. Schulklassen werden nur betreut statt vertreten. Unterricht entf\u00e4llt und Sch\u00fclerinnen und Sch\u00fcler f\u00fchlen sich nicht gut auf Abschlusspr\u00fcfungen vorbereitet \u2013 die Folgen des Lehrermangels sind an der Gesamtschule Barmen jeden Tag zu sp\u00fcren. Und ausgerechnet jetzt haben \u00fcber 15 Lehrkr\u00e4fte die Schule verlassen, weil sie in den Ruhestand gegangen sind oder eine Versetzung beantragt haben. Wie gro\u00df ist das Problem des Lehrermangels? Und wann ist Besserung in Sicht?&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.6\">Aus Sicht der Sch\u00fclerinnen und Sch\u00fcler ist es vielleicht gar nicht so schlimm, wenn mal Unterricht ausf\u00e4llt. Oft sind sie eher gl\u00fccklich dar\u00fcber, einmal keinen Chemieunterricht zu haben. Aber inwiefern ist das hilfreich? Am Ende geraten dadurch Noten und sogar Abschl\u00fcsse in Gefahr.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.6\">An unserer Schule fehlten bereits im letzten Jahr acht Lehrerstellen \u2013 die Schule ist im Stellenunterhang, wie es im Beamtendeutsch hei\u00dft. Mit Ende des Schuljahres 2023\/2024 gingen weitere Lehrkr\u00e4fte, wodurch die Zahl der Besch\u00e4ftigten auf 96 st\u00fcrzte. Dazu muss man wissen: Etwa 120 Lehrerinnen und Lehrer werden an der Gesamtschule Barmen gebraucht. Der gr\u00f6\u00dfte Mangel herrscht in den naturwissenschaftlichen F\u00e4chern wie Chemie und Mathe.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.6\">Das Deutsche Schulportal der Robert Bosch Stiftung rechnete aus, dass bis zum Jahr 2035 68.000 Lehrkr\u00e4fte fehlen werden. Zum Vergleich: Das ist so, als w\u00fcrden 566 Gesamtschulen Barmen leer stehen. Noch schlimmer wird es dadurch, dass keine neuen Lehrer dazu kommen. Die Attraktivit\u00e4t des Lehrerberufs sinkt aus einigen Gr\u00fcnden, welche vor allem die Arbeitsbedingungen betreffen. Das bedeutet, dass diese weniger Anerkennung erhalten, oder dass Quereinsteiger und Lehrer F\u00e4cher \u00fcbernehmen, f\u00fcr die sie nicht geeignet sind bzw. nicht ausgebildet wurden.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.6\">\u201cF\u00fcr den Lehrkraftmangel gibt es keine schnelle und vor allem keine einfache L\u00f6sung\u201d, res\u00fcmiert Dagmar Wolf von der Robert Bosch Stiftung. Wir m\u00fcssen nun damit leben, dass wir f\u00fcr eine l\u00e4ngere Zeit nicht in allen F\u00e4chern immer gef\u00f6rdert werden k\u00f6nnen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nachtrag aus der Redaktion:<\/strong> Mittlerweile (Schuljahr 2025\/26) hat die Gesamtschule Barmen wieder viele Stellen besetzen k\u00f6nnen. Trotzdem macht sich der beschriebene Mangel in unserer Stadt stark bemerkbar und wird in den n\u00e4chsten Schuljahren lokal noch zu gro\u00dfen Herausforderungen f\u00fchren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mathematik wird von drei Stunden die Woche auf zwei gek\u00fcrzt. Schulklassen werden nur betreut statt vertreten. Unterricht entf\u00e4llt und Sch\u00fclerinnen und Sch\u00fcler f\u00fchlen sich nicht gut auf Abschlusspr\u00fcfungen vorbereitet \u2013 die Folgen des Lehrermangels sind an der Gesamtschule Barmen jeden Tag zu sp\u00fcren. Und ausgerechnet jetzt haben \u00fcber 15 Lehrkr\u00e4fte die Schule verlassen, weil sie [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":68,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-31","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politikundgesellschaft"],"_links":{"self":[{"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/posts\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/comments?post=31"}],"version-history":[{"count":14,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/posts\/31\/revisions"}],"predecessor-version":[{"id":481,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/posts\/31\/revisions\/481"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/media\/68"}],"wp:attachment":[{"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/media?parent=31"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/categories?post=31"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/tuffistagespresse.gesamtschule-barmen.de\/index.php\/wp-json\/wp\/v2\/tags?post=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}